{"id":13528,"date":"2012-03-14T22:41:24","date_gmt":"2012-03-14T21:41:24","guid":{"rendered":"http:\/\/airtimers.com\/?p=13528"},"modified":"2012-03-15T09:43:25","modified_gmt":"2012-03-15T08:43:25","slug":"parques-reunidos-ubernimmt-den-attractiepark-slagharen","status":"publish","type":"post","link":"https:\/\/airtimers.com\/en\/parques-reunidos-ubernimmt-den-attractiepark-slagharen\/0013528\/","title":{"rendered":"Parques Reunidos \u00fcbernimmt den Attractiepark Slagharen"},"content":{"rendered":"<p>Nach 49 Jahren hat die Familie Bemboom den Park &#8220;Attractiepark Slagharen&#8221; verkauft. K\u00e4ufer des niederl\u00e4ndischen Freizeitparks samt Feriendorf ist das Spanische Unternehmen &#8220;Parques Reunidos&#8221;, welchem unter anderem auch das &#8220;Bobbejaanland&#8221;, die Spanischen Parks \u201eParque Warner\u201c und \u201eParque de Atracciones\u201c, seit letzdem Jahr der &#8220;Movie Park Germany&#8221; und noch viele weitere Freizeitparks, Wasserparks und andere Ausflugsziele in Europa und den USA geh\u00f6rt.<\/p>\n<p><center><iframe loading=\"lazy\" width=\"475\" height=\"352\" src=\"http:\/\/www.youtube.com\/embed\/UyHqjEPSGpk?rel=0\" frameborder=\"0\" allowfullscreen><\/iframe><\/center><\/p>\n<p>Nachdem der Kauf lange Zeit in der Luft hing, wurde der Park, welcher im Jahr 1963 von Henk Bemboom gegr\u00fcndet wurde und damals als \u201ePonypark Slagharen\u201c bekannt war, nun gekauft. Erste Gespr\u00e4che \u00fcber eine \u00dcbernahme gab es bereits im letzten Jahr, allerdings hatte Angelique Klar, die Managerin des Parks, einen Verkauf zu diesem Zeitpunkt noch abgelehnt, aber betont, dass er nicht ausgeschlossen sei. Wann Parques Reunidos offiziell die Leitung \u00fcbernimmt und ob der Park ein neues Management bekommt, ist noch nicht bekannt.<\/p>\n<p>Verfasst von unserem Foren-VIP Ren\u00e9<br \/>\nPictures and Video: Copyright Ontdek \/ Attractiepark Slagharen<\/p>\n<fb:like href='https:\/\/airtimers.com\/en\/parques-reunidos-ubernimmt-den-attractiepark-slagharen\/0013528\/' send='false' layout='standard' show_faces='true' width='450' height='65' action='like' colorscheme='light' font='lucida grande'><\/fb:like>","protected":false},"excerpt":{"rendered":"<p>Nach 49 Jahren hat die Familie Bemboom den Park &#8220;Attractiepark Slagharen&#8221; verkauft. K\u00e4ufer des niederl\u00e4ndischen Freizeitparks samt Feriendorf ist das Spanische Unternehmen &#8220;Parques Reunidos&#8221;, welchem unter anderem auch das &#8220;Bobbejaanland&#8221;, die Spanischen Parks \u201eParque Warner\u201c und \u201eParque de Atracciones\u201c, seit letzdem Jahr der &#8220;Movie Park Germany&#8221; und noch viele weitere Freizeitparks, Wasserparks und andere Ausflugsziele [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":13529,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[234,589],"class_list":["post-13528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-freizeitparks","tag-parques-reunidos","tag-slagharen"],"_links":{"self":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/posts\/13528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/comments?post=13528"}],"version-history":[{"count":0,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/posts\/13528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/media\/13529"}],"wp:attachment":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/media?parent=13528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/categories?post=13528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/tags?post=13528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}