{"id":14629,"date":"2012-06-28T22:57:03","date_gmt":"2012-06-28T20:57:03","guid":{"rendered":"http:\/\/airtimers.com\/?p=14629"},"modified":"2012-06-28T23:43:39","modified_gmt":"2012-06-28T21:43:39","slug":"tokyo-disneysea-an-die-spielzeugkanonen-fertig-los","status":"publish","type":"post","link":"https:\/\/airtimers.com\/en\/tokyo-disneysea-an-die-spielzeugkanonen-fertig-los\/0014629\/","title":{"rendered":"Tokyo DisneySea &#8211; An die Spielzeugkanonen, fertig, los!"},"content":{"rendered":"<p>Ab geht die wilde Zockerei im Toy Story-Universum! Ab dem 9. Juli k\u00f6nnen gro\u00dfe und kleine Disneyfans in der Hauptstadt den mittlerweile dritten Ableger des \u00e4u\u00dferst beliebten interaktiven 3D-Darkride &#8220;Toy Story Mania!&#8221; erleben und sich Herz und Seele aus dem Leib schie\u00dfen. Diese Attraktion hat ihren Platz in einem kleinen, eigens eingerichteten Bereich im &#8220;Waterfront USA&#8221;-Sektor erhalten, womit die stilistischen und architektonischen Unterschiede nicht allzu schwer ins Gewicht fallen d\u00fcrften.<\/p>\n<div id=\"attachment_14630\" style=\"width: 485px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14630\" src=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2012\/06\/Tokyo-Disney-Sea-Toy-Story-Mania-1.jpg\" alt=\"\" title=\"Tokyo-Disney-Sea-Toy-Story-Mania-1\" width=\"475\" height=\"285\" class=\"size-full wp-image-14630 colorbox-14629\" srcset=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2012\/06\/Tokyo-Disney-Sea-Toy-Story-Mania-1.jpg 475w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2012\/06\/Tokyo-Disney-Sea-Toy-Story-Mania-1-300x180.jpg 300w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2012\/06\/Tokyo-Disney-Sea-Toy-Story-Mania-1-170x102.jpg 170w\" sizes=\"auto, (max-width: 475px) 100vw, 475px\" \/><p id=\"caption-attachment-14630\" class=\"wp-caption-text\">Der Eingang des Ballerrides wird von einem gigantischen Woodie-Kopf dominiert!<\/p><\/div>\n<p>Die Gestaltung des &#8220;Toy Ville Trolley Park&#8221; &#8211; so der Name jenes Bereiches &#8211; orientiert sich hierbei an verschiedenen historischen Freizeitparks, wie beispielsweise dem ber\u00fchmten Coney Island Luna Parks in New York City oder dem Luna Park in der gr\u00f6\u00dften Stadt Australiens, Sydney. Neben dem 3D-Darkride werden noch weitere Boardwalk-\u00e4hnliche Spiele den G\u00e4sten zur Vergn\u00fcgung bereitstehen. Sorgen um Langeweile sollte man sich also definitiv nicht machen!<\/p>\n<div id=\"attachment_14631\" style=\"width: 485px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14631\" src=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2012\/06\/Tokyo-Disney-Sea-Toy-Story-Mania-2.jpg\" alt=\"\" title=\"Tokyo-Disney-Sea-Toy-Story-Mania-2\" width=\"475\" height=\"285\" class=\"size-full wp-image-14631 colorbox-14629\" srcset=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2012\/06\/Tokyo-Disney-Sea-Toy-Story-Mania-2.jpg 475w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2012\/06\/Tokyo-Disney-Sea-Toy-Story-Mania-2-300x180.jpg 300w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2012\/06\/Tokyo-Disney-Sea-Toy-Story-Mania-2-170x102.jpg 170w\" sizes=\"auto, (max-width: 475px) 100vw, 475px\" \/><p id=\"caption-attachment-14631\" class=\"wp-caption-text\">Der Blick vom Toy Ville Trolley Park - der Traum eines jeden Disneyfans!<\/p><\/div>\n<p>Bleibt lediglich abzuwarten, inwiefern sich der Run auf die Attraktion in den Wartezeiten widerspiegelt. Bei den anderen Spielzeugballer-Ablegern in Orlando und Anaheim sind Wartezeiten jenseits von Gut, B\u00f6se und der 60-Minuten-Marke bereits mehr als Standart &#8211; wobei die Tokyoter Parks dort vermutlich noch einmal einen drauflegen werden. Wenn man sich nur die regelm\u00e4\u00dfige Stand-By-Entrance-Zeitanzeige von &#8220;Journey to the Center of the Earth&#8221; oder des Monsters Inc. Darkrides anschaut, ahnt man nicht nur Grauenvolles, sondern vermutlich die (Spiel-)H\u00f6lle auf Erden! In dem Sinne: let the games begin!<\/p>\n<p><center><iframe loading=\"lazy\" width=\"475\" height=\"267\" src=\"http:\/\/www.youtube.com\/embed\/tmDgcS4a2mY?rel=0\" frameborder=\"0\" allowfullscreen><\/iframe><\/center><\/p>\n<p>Bildquelle: Disneyandmore.com<\/p>\n<fb:like href='https:\/\/airtimers.com\/en\/tokyo-disneysea-an-die-spielzeugkanonen-fertig-los\/0014629\/' send='false' layout='standard' show_faces='true' width='450' height='65' action='like' colorscheme='light' font='lucida grande'><\/fb:like>","protected":false},"excerpt":{"rendered":"<p>Ab geht die wilde Zockerei im Toy Story-Universum! Ab dem 9. Juli k\u00f6nnen gro\u00dfe und kleine Disneyfans in der Hauptstadt den mittlerweile dritten Ableger des \u00e4u\u00dferst beliebten interaktiven 3D-Darkride &#8220;Toy Story Mania!&#8221; erleben und sich Herz und Seele aus dem Leib schie\u00dfen. Diese Attraktion hat ihren Platz in einem kleinen, eigens eingerichteten Bereich im &#8220;Waterfront [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":14630,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[406,554,26],"class_list":["post-14629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disney-parks","tag-disneyland-tokyo","tag-disneysea","tag-toy-story"],"_links":{"self":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/posts\/14629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/comments?post=14629"}],"version-history":[{"count":0,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/posts\/14629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/media\/14630"}],"wp:attachment":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/media?parent=14629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/categories?post=14629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/tags?post=14629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}