{"id":37368,"date":"2018-05-21T21:47:48","date_gmt":"2018-05-21T19:47:48","guid":{"rendered":"http:\/\/airtimers.com\/?p=37368"},"modified":"2018-05-21T21:47:48","modified_gmt":"2018-05-21T19:47:48","slug":"probleme-bei-ratatouille-im-walt-disney-studios-park-paris","status":"publish","type":"post","link":"https:\/\/airtimers.com\/en\/probleme-bei-ratatouille-im-walt-disney-studios-park-paris\/0037368\/","title":{"rendered":"Probleme bei Ratatouille im Walt Disney Studios Park Paris"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/airtimers.com\/de\/wp-json\/wp\/v2\/posts\/37368\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>. For the sake of viewer convenience, the content is shown below in the alternative language. You may click the link to switch the active language.<\/p>Es ist die letzte gro\u00dfe Attraktion, welche im Pariser Disney Resort er\u00f6ffnet wurde. Die Rede ist vom 2014 er\u00f6ffneten Darkride <em>Ratatouille<\/em> im &#8211; zum <em>Disneyland Paris<\/em> benachbarten &#8211; <em>Walt Disney Studios Park<\/em>. Die Themenfahrt rund um den Disneyfilm <em>Ratatouille<\/em> verf\u00fcgt dabei \u00fcber eine Mischung aus realer Szenen sowie 3D-Screens, welche die Fahrg\u00e4ste auf die Gr\u00f6\u00dfe einer Ratte schrumpfen lassen. <\/p>\n<div id=\"attachment_37370\" style=\"width: 2710px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2018\/05\/Ratatouille-2.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-37370\" src=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2018\/05\/Ratatouille-2.jpg\" alt=\"\" width=\"2700\" height=\"1519\" class=\"size-full wp-image-37370 colorbox-37368\" srcset=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2018\/05\/Ratatouille-2.jpg 2700w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2018\/05\/Ratatouille-2-300x169.jpg 300w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2018\/05\/Ratatouille-2-768x432.jpg 768w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2018\/05\/Ratatouille-2-1024x576.jpg 1024w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2018\/05\/Ratatouille-2-810x456.jpg 810w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2018\/05\/Ratatouille-2-1140x641.jpg 1140w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2018\/05\/Ratatouille-2-600x338.jpg 600w\" sizes=\"auto, (max-width: 2700px) 100vw, 2700px\" \/><\/a><p id=\"caption-attachment-37370\" class=\"wp-caption-text\">Pariser Flair im Pariser Disney-Park<\/p><\/div>\n<p>Seit einiger Zeit gibt es aber immer wieder Probleme mit der Bahn und so kam es bereits des \u00d6fteren dazu, dass die Attraktion geschlossen blieb. Grund daf\u00fcr soll das Absacken des Fundamentes sein. Laut Aussage des operativen Direktors <em>Daniel Delcourt<\/em>, wurden beim Bau der Anlage Fehler gemacht, welche sich nun bemerkbar machen. So gibt es durch das Absacken des Fundamentes vor allem massive Probleme mit der \u00dcbertragung der Steuersignale f\u00fcr das schienenlose Fahrsystem.<\/p>\n<p>Aus diesem Grund wird <em>Ratatouille<\/em> nun f\u00fcr den Zeitraum von August bis Dezember 2018 geschlossen bleiben, um das Problem in den Griff zu bekommen.<br \/>\nPleiten, Pech und Pannen scheint es in Paris leider des \u00d6fteren zu geben, hoffen wir das sich das nun in der Zukunft alles verbessert.<\/p>\n<p>Pictures: Copyright Disney\n<fb:like href='https:\/\/airtimers.com\/en\/probleme-bei-ratatouille-im-walt-disney-studios-park-paris\/0037368\/' send='false' layout='standard' show_faces='true' width='450' height='65' action='like' colorscheme='light' font='lucida grande'><\/fb:like>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Deutsch. For the sake of viewer convenience, the content is shown below in the alternative language. You may click the link to switch the active language.Es ist die letzte gro\u00dfe Attraktion, welche im Pariser Disney Resort er\u00f6ffnet wurde. Die Rede ist vom 2014 er\u00f6ffneten Darkride Ratatouille im &#8211; [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":37369,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[214,84],"class_list":["post-37368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disney-parks","tag-disneyland-paris","tag-ratatouille"],"_links":{"self":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/posts\/37368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/comments?post=37368"}],"version-history":[{"count":0,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/posts\/37368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/media\/37369"}],"wp:attachment":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/media?parent=37368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/categories?post=37368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/tags?post=37368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}