{"id":42404,"date":"2020-11-30T11:09:39","date_gmt":"2020-11-30T10:09:39","guid":{"rendered":"https:\/\/airtimers.com\/?p=42404"},"modified":"2020-11-30T11:09:39","modified_gmt":"2020-11-30T10:09:39","slug":"eroeffnungstermin-und-neue-bilder-aus-super-nintendo-world","status":"publish","type":"post","link":"https:\/\/airtimers.com\/en\/eroeffnungstermin-und-neue-bilder-aus-super-nintendo-world\/0042404\/","title":{"rendered":"Er\u00f6ffnungstermin und neue Bilder aus Super Nintendo World!"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/airtimers.com\/de\/wp-json\/wp\/v2\/posts\/42404\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>. For the sake of viewer convenience, the content is shown below in the alternative language. You may click the link to switch the active language.<\/p>Eigentlich war es unsere pers\u00f6nliche Top-Neuheit des Jahres 2020 &#8211; daraus wurde nun allerdings aus bekannten Gr\u00fcnden nichts. Nun gibt es aber endlich neue Bilder aus dem neuen Themenbereich der Universal Studios Japan &#8211; der Super Nintendo World!<br \/>\nDie beeindruckenden Bilder zeigen eine Totale auf das Themenland, welche einen erst ein wenig zweifeln l\u00e4sst, ob es sich um eine Animation oder um den realen Themenbereich handelt.<br \/>\nUniversal hat es geschafft das optische perfekte Videospiel zu schaffen!<br \/>\nZus\u00e4tzlich gibt es erste Bilder aus der neuen Attraktion zum Spieleklassiker Mario Kart! Hierbei wurde Bowsers Castle nachgebaut. Das Besondere an diesem Ride wird nicht nur die Interaktion mit anderen Rennteilnehmern, sondern auch die Verwendung von sogenannten AR (Augmented Reality) Brillen sein! Diese Technik der erweiterten Realit\u00e4t erm\u00f6glicht die Einblendung von bekannten Spielobjekten wie beispielsweise Bananen, Bomben oder die roten und gr\u00fcnen Panzer! Somit soll jede Fahrt anders sein und auch unterschiedliche Rennsieger sind ein Spannungseffekt! Die Brillen sehen dabei aus wie M\u00fctzen des Hauptcharackters &#8211; Mario.<\/p>\n<div id=\"attachment_42410\" style=\"width: 790px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/Nintendo-1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-42410\" src=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/Nintendo-1.jpg\" alt=\"\" width=\"780\" height=\"470\" class=\"size-full wp-image-42410 colorbox-42404\" srcset=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/Nintendo-1.jpg 780w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/Nintendo-1-300x181.jpg 300w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/Nintendo-1-768x463.jpg 768w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/Nintendo-1-475x285.jpg 475w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/Nintendo-1-600x362.jpg 600w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/a><p id=\"caption-attachment-42410\" class=\"wp-caption-text\">Die Wagen des Mario-Kart-Rides<\/p><\/div>\n<p>Die Er\u00f6ffnung des neuen Themenbereiches ist f\u00fcr den 4. Februar 2021 geplant &#8211; vorausgesetzt die Corona-Lage bleibt stabil!<br \/>\nIn Zukunft soll es sogar noch eine Erweiterung zu Donkey Kong geben! <\/p>\n<p><a href=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730285334.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730285334-1024x683.jpg\" alt=\"\" width=\"810\" height=\"540\" class=\"aligncenter size-large wp-image-42408 colorbox-42404\" srcset=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730285334-1024x683.jpg 1024w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730285334-300x200.jpg 300w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730285334-768x512.jpg 768w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730285334-810x540.jpg 810w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730285334-600x400.jpg 600w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730285334.jpg 1080w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730289579.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730289579-1024x683.jpg\" alt=\"\" width=\"810\" height=\"540\" class=\"aligncenter size-large wp-image-42409 colorbox-42404\" srcset=\"https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730289579-1024x683.jpg 1024w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730289579-300x200.jpg 300w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730289579-768x512.jpg 768w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730289579-810x540.jpg 810w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730289579-600x400.jpg 600w, https:\/\/airtimers.com\/blog\/wp-content\/uploads\/2020\/11\/FB_IMG_1606730289579.jpg 1080w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n<p>Pictures: Copyright Universal Studios Japan\n<fb:like href='https:\/\/airtimers.com\/en\/eroeffnungstermin-und-neue-bilder-aus-super-nintendo-world\/0042404\/' send='false' layout='standard' show_faces='true' width='450' height='65' action='like' colorscheme='light' font='lucida grande'><\/fb:like>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Deutsch. For the sake of viewer convenience, the content is shown below in the alternative language. You may click the link to switch the active language.Eigentlich war es unsere pers\u00f6nliche Top-Neuheit des Jahres 2020 &#8211; daraus wurde nun allerdings aus bekannten Gr\u00fcnden nichts. Nun gibt es aber endlich [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":42411,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1828,1827],"class_list":["post-42404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-freizeitparks","tag-mario","tag-super-nintendo-world"],"_links":{"self":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/posts\/42404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/comments?post=42404"}],"version-history":[{"count":0,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/posts\/42404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/media\/42411"}],"wp:attachment":[{"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/media?parent=42404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/categories?post=42404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/airtimers.com\/en\/wp-json\/wp\/v2\/tags?post=42404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}